
{"id":1430817,"date":"2020-03-27T09:41:35","date_gmt":"2020-03-27T08:41:35","guid":{"rendered":"https:\/\/staging-wp-int.laboklin.com\/laboklin-sonder-news\/"},"modified":"2022-11-22T11:49:32","modified_gmt":"2022-11-22T10:49:32","slug":"laboklin-sonder-news","status":"publish","type":"page","link":"https:\/\/laboklin.com\/no\/laboklin-sonder-news\/","title":{"rendered":"LABOKLIN Sonder-News"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column css=&raquo;.vc_custom_1585301375144{margin-top: -30px !important;margin-bottom: 30px !important;}&raquo;][vc_single_image image=&raquo;3718&#8243; img_size=&raquo;full&raquo; alignment=&raquo;right&raquo;][\/vc_column][\/vc_row][vc_row][vc_column]<style type=\"text\/css\" data-type=\"the7_shortcodes-inline-css\">.blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae.side-overlap-layout-list .post-thumbnail-wrap {\n  width: 60%;\n}\n.blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae.side-overlap-layout-list .post-entry-content {\n  width: calc(100% - 60% + 150px);\n  margin-top: 50px;\n}\n.blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae.side-overlap-layout-list .no-img .post-entry-content {\n  width: 100%;\n  margin-top: 0;\n}\n.blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae.side-overlap-layout-list .project-odd .post-entry-content {\n  margin-left: -150px;\n}\n.rtl .blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae.side-overlap-layout-list .project-odd .post-entry-content {\n  margin-right: -150px;\n  margin-left: 0;\n}\n.blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae.side-overlap-layout-list .no-img.project-odd .post-entry-content {\n  margin-left: 0;\n}\n.rtl .blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae.side-overlap-layout-list .no-img.project-odd .post-entry-content {\n  margin-right: 0;\n  margin-left: 0;\n}\n.blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae.side-overlap-layout-list .project-even .post-entry-content {\n  margin-right: -150px;\n}\n.rtl .blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae.side-overlap-layout-list .project-even .post-entry-content {\n  margin-left: -150px;\n  margin-right: 0;\n}\n.blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae.side-overlap-layout-list .no-img.project-even .post-entry-content {\n  margin-right: 0;\n}\n.rtl .blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae.side-overlap-layout-list .no-img.project-even .post-entry-content {\n  margin-left: 0;\n  margin-right: 0;\n}\n@media screen and (max-width: 768px) {\n  #page .blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae.side-overlap-layout-list .project-odd .post-entry-content {\n    left: 0;\n  }\n  #page .blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae.side-overlap-layout-list .project-even .post-entry-content {\n    right: 0;\n  }\n}\n.blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae .filter-bg-decoration .filter-categories a.act {\n  color: #fff;\n}\n.blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae:not(.mode-masonry) article {\n  margin-top: 50px;\n}\n.blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae:not(.mode-masonry) article:first-of-type,\n.blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae:not(.mode-masonry) article.visible.first:not(.product) {\n  margin-top: 0;\n}\n.blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae.dividers-on:not(.mode-masonry) article {\n  margin-top: 0;\n  padding-top: 50px;\n}\n.blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae.dividers-on:not(.mode-masonry) article:first-of-type,\n.blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae.dividers-on:not(.mode-masonry) article.visible.first:not(.product) {\n  margin-top: 0;\n  padding-top: 0;\n}\n.blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae .post-thumbnail-wrap {\n  padding: 0px 0px 0px 0px;\n}\n.blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae.enable-bg-rollover .post-thumbnail-rollover:after {\n  background: -webkit-linear-gradient();\n  background: linear-gradient();\n}\n.blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae .gallery-zoom-ico {\n  width: 44px;\n  height: 44px;\n  line-height: 44px;\n  border-radius: 100px;\n  margin: -22px 0 0 -22px;\n  border-width: 0px;\n  color: #ffffff;\n}\n.bottom-overlap-layout-list.blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae .gallery-zoom-ico {\n  margin-top: -47px;\n}\n.gradient-overlay-layout-list.blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae .gallery-zoom-ico,\n.content-rollover-layout-list.blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae .gallery-zoom-ico {\n  margin: 0 0 10px;\n}\n.content-align-center.gradient-overlay-layout-list.blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae .gallery-zoom-ico,\n.content-align-center.content-rollover-layout-list.blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae .gallery-zoom-ico {\n  margin: 0 auto 10px;\n}\n.dt-icon-bg-on.blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae .gallery-zoom-ico {\n  background: rgba(255,255,255,0.3);\n  box-shadow: none;\n}\n.blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae .gallery-zoom-ico > span,\n.blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae .gallery-zoom-ico:before {\n  font-size: 32px;\n  line-height: 44px;\n}\n.blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae .gallery-zoom-ico > span,\n.blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae .gallery-zoom-ico:before {\n  color: #ffffff;\n}\n.blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae .fancy-date a {\n  background: #ffffff;\n  box-shadow: none;\n}\n.blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae .fancy-date a * {\n  color: #2d2d2d;\n}\n.blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae .fancy-categories a {\n  color: #232323;\n  background: #ffdd00;\n  box-shadow: none;\n}\n.blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae .entry-title,\n.blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae.owl-carousel .entry-title {\n  margin-bottom: 5px;\n  font-weight: bold;\n}\n.blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae .entry-meta {\n  margin-bottom: 15px;\n}\n.blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae .portfolio-categories {\n  margin-bottom: 15px;\n}\n.blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae .entry-excerpt {\n  margin-bottom: 5px;\n}\n.blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae:not(.centered-layout-list) .post-entry-content {\n  padding: 25px 30px 30px 30px;\n}\n.blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae:not(.centered-layout-list):not(.content-bg-on):not(.mode-list) .no-img .post-entry-content {\n  padding: 0;\n}\n@media screen and (max-width: 768px) {\n  .blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae article {\n    -ms-flex-flow: column nowrap;\n    flex-flow: column nowrap;\n    margin-top: 20px;\n  }\n  .blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae.dividers-on article {\n    border: none;\n  }\n  .blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae.content-bg-on.centered-layout-list article {\n    padding: 0;\n  }\n  .blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae.blog-shortcode.dividers-on article,\n  .blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae.dividers-on.classic-layout-list article {\n    margin-top: 20px;\n    padding: 0;\n  }\n  .blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae.blog-shortcode.dividers-on article:first-of-type,\n  .blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae.dividers-on.classic-layout-list article:first-of-type {\n    padding: 0;\n  }\n  #page .blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae .post-thumbnail-wrap,\n  #page .blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae .post-entry-content {\n    width: 100%;\n    margin: 0;\n    top: 0;\n  }\n  #page .blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae .post-thumbnail-wrap {\n    padding: 0;\n  }\n  #page .blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae .post-entry-content:after {\n    display: none;\n  }\n  #page .blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae .project-even .post-thumbnail-wrap,\n  #page .blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae.centered-layout-list .post-thumbnail-wrap {\n    -ms-flex-order: 0;\n    order: 0;\n  }\n  #page .blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae.centered-layout-list .post-entry-title-content {\n    -ms-flex-order: 1;\n    order: 1;\n    width: 100%;\n    padding: 20px 20px 0;\n  }\n  #page .blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae.centered-layout-list .post-entry-content {\n    -ms-flex-order: 2;\n    order: 2;\n    padding-top: 0;\n  }\n  #page .blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae .fancy-categories {\n    top: 10px;\n    left: 10px;\n    bottom: auto;\n    right: auto;\n  }\n  #page .blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae .fancy-date a {\n    top: 10px;\n    right: 10px;\n    left: auto;\n    bottom: auto;\n  }\n  #page .blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae .post-entry-content {\n    padding: 20px;\n  }\n  #page .blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae .entry-title {\n    margin: 3px 0 5px;\n    font-size: 20px;\n    line-height: 26px;\n  }\n  #page .blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae .entry-meta {\n    margin: 5px 0 5px;\n  }\n  #page .blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae .entry-excerpt {\n    margin: 15px 0 0;\n  }\n  #page .blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae .post-details {\n    margin: 5px 0 10px;\n  }\n  #page .blog-shortcode.blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae .post-details.details-type-link {\n    margin-bottom: 2px;\n  }\n}<\/style><div class=\"articles-list blog-shortcode mode-list blog-list-shortcode-id-d704a2da0b3e4625cabe89a484c7e0ae side-overlap-layout-list content-bg-on jquery-filter lazy-loading-mode scale-img dt-icon-bg-off vertical-fancy-style loading-effect-fade-in\" data-cur-page=\"1\" data-post-limit=\"10\" data-pagination-mode=\"load-more\" aria-live=\"assertive\"><div class=\"paginator paginator-more-button\">\n\t\t\t\t<a class=\"button-load-more \" href=\"javascript:void(0);\" data-dt-page=\"1\" ><span class=\"stick\"><\/span><span class=\"stick\"><\/span><span class=\"stick\"><\/span><span class=\"button-caption\">Load more<\/span><\/a>\n\t\t\t<\/div><\/div>[\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column css=&raquo;.vc_custom_1585301375144{margin-top: -30px !important;margin-bottom: 30px !important;}&raquo;][vc_single_image image=&raquo;3718&#8243; img_size=&raquo;full&raquo; alignment=&raquo;right&raquo;][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":25,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":""},"class_list":["post-1430817","page","type-page","status-publish","hentry","description-off"],"_links":{"self":[{"href":"https:\/\/laboklin.com\/no\/wp-json\/wp\/v2\/pages\/1430817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laboklin.com\/no\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/laboklin.com\/no\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/laboklin.com\/no\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laboklin.com\/no\/wp-json\/wp\/v2\/comments?post=1430817"}],"version-history":[{"count":0,"href":"https:\/\/laboklin.com\/no\/wp-json\/wp\/v2\/pages\/1430817\/revisions"}],"wp:attachment":[{"href":"https:\/\/laboklin.com\/no\/wp-json\/wp\/v2\/media?parent=1430817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}