{"id":1466386,"date":"2021-02-17T14:51:24","date_gmt":"2021-02-17T13:51:24","guid":{"rendered":"https:\/\/laboklin.com\/?p=1466386"},"modified":"2024-09-05T13:39:09","modified_gmt":"2024-09-05T11:39:09","slug":"vaccini-e-test-sierologici-nel-cavallo","status":"publish","type":"post","link":"https:\/\/laboklin.com\/it\/vaccini-e-test-sierologici-nel-cavallo\/","title":{"rendered":"Vaccini e test sierologici nel cavallo"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]Nella clinica ippiatrica abbiamo a disposizione alcuni vaccini per la prevenzione di patologie virali e batteriche; questi protocolli vaccinali possono interferire nella diagnostica sierologica anticorpale \u2013 vediamo come e per quali malattie.<\/p>\n<h2>Principi generali<\/h2>\n<p>Un vaccino non fa altro che veicolare l\u2019antigene di un patogeno mettendolo in contatto con le cellule linfoidi nei linfonodi tramite il sistema linfatico o nella milza, tramite il circolo sanguigno. I linfociti B inglobano l\u2019antigene che gli viene presentato, interagiscono coi linfociti T e cominciano a produrre anticorpi (prima IgM, poi IgG, IgA, IgE) diventando plasmacellule; in seguito alcuni linfociti B diventano \u201cmemory cell\u201d pronte ad attivarsi se nuovamente esposti al medesimo antigene. Anche alcuni linfociti T, incontrando gli stessi antigeni, si attivano in aiuto dei linfociti B nella modulazione della risposta immunitaria (linfociti T helper): alcuni di questi diventano linfociti T \u201cmemory\u201d, preparati per affrontare un\u2019eventuale infezione naturale.<\/p>\n<h2>Adiuvanti<\/h2>\n<p>La stimolazione antigenica data dal vaccino viene amplificata dagli adiuvanti nel caso di un vaccino spento, che cio\u00e8 non replica nell\u2019organismo e che quindi potrebbe non venire in contatto con molte cellule linfoidi. Gli adiuvanti sono sostanze che promuovono l\u2019infiammzione nel sito di inoculo, per richiamare pi\u00f9 cellule possibili, che poi presenteranno l\u2019antigene ad un maggior numero di linfociti, ottimizzando ed amplificando quindi Ia risposta immunitaria.<\/p>\n<p>Le sostanze utilizzate principalmente come adiuvanti sono: sali di alluminio, emulsioni, particelle lipidiche, nanoparticelle, polielettroliti, immunopotenziatori (proteine, glicosidi).<\/p>\n<h2>Vaccini<\/h2>\n<p>I principali vaccini studiati per il cavallo sono di varia tipologia:<\/p>\n<ul>\n<li><em>vivi attenuati:<\/em>\u00a0sono prodotti inattivando l\u2019agente eziologico che perde quindi la sua patogenicit\u00e0, conservando nel contempo la piena immunogenicit\u00e0, anche attraverso un\u2019attiva replicazione all\u2019interno dell\u2019ospite, senza peraltro causare la malattia.<\/li>\n<li><em>inattivati<\/em>: sono composti dagli agenti eziologici uccisi tramite calore, formaldeide, irradiazione; per questo motivo sono meno immunogeni ed usualmente abbinati ad adiuvanti per permettere una maggior reattivit\u00e0 immunologica.<\/li>\n<li><em>a subunit\u00e0 proteiche<\/em>: contengono le porzioni proteiche degli agenti eziologici o delle tossine che producono una forte risposta immunitaria senza altre azioni patogene nei confronti dell\u2019ospite; sono di solito addizionati adiuvanti.<\/li>\n<li><em>ricombinanti:<\/em> sono composti da un antigene \u201cinnestato\u201d su un virus vettore sicuramente non patogeno per il cavallo (poxvirus del canarino ad esempio), che replica contribuendo alla produzione di una forte risposta immunitaria, sia umorale che cellulo-mediata.<\/li>\n<li><em>a DNA:<\/em> sono prodotti inserendo la sequenza genica che codifica per alcune proteine virali di superficie in plasmidi batterici che colonizzano la cellula linfocitaria facendole produrre essa stessa la proteina immunogena. Questa di seguito viene esposta dalle stesse cellule del sistema immunitario determinando una rapida attivazione sia umorale che cellulomediata.<\/li>\n<li><em>chimerici<\/em>: sono composti da pi\u00f9 sequenze geniche che codificano per differenti proteine dell\u2019envelope o del capside virale.<\/li>\n<\/ul>\n<p>Vediamo in dettaglio per ogni vaccino disponibile sul mercato italiano le tempistiche di somministrazione, di insorgenza e durata dell\u2019immunit\u00e0 vaccinale, per una corretta interpretazione dei corrispettivi test sierologici disponibili.<\/p>\n<h2>Tetano<\/h2>\n<p>Si tratta di una patologia grave causata da\u00a0<em>Clostridium tetani<\/em>. Il microrganismo penetra attraverso ferite cutanee, anche di lieve entit\u00e0, in contatto con il terreno dove le spore del batterio sono abbondanti. Dopo l\u2019infezione il microrganismo inizia a produrre la tossina che, raggiungendo il sistema nervoso periferico e poi centrale, \u00e8 la responsabile della sintomatologia neurologica paralitica che porta quasi inevitabilmente alla morte il soggetto colpito.<\/p>\n<p>Il vaccino viene allestito con il tossoide tetanico (od anatossina), che sarebbe la parte immunogena della\u00a0<em>tetanospasmina<\/em>, priva del suo potere tossico.<\/p>\n<p>Se invece si ha necessit\u00e0 di protezione immediata, \u00e8 possibile somministrare entro 24 ore dall\u2019evento a rischio (ferita, chiodo nello zoccolo, parto\u2026) il\u00a0<em>siero iperimmune antitetanico<\/em>, contenente le immunoglobuline gi\u00e0 pronte, prodotte da un soggetto vaccinato, con un effetto protettivo da 24-48 ore dopo somministrazione intramuscolare ed immediatamente dopo somministrazione endovenosa, fino a circa 20 giorni post inoculo.<\/p>\n<p>Nel frattempo, nei soggetti adulti \u00e8 anche possibile somministrare il vaccino contemporaneamente al siero iperimmune, in parti muscolari differenti, a completamento della protezione immunitaria.<\/p>\n<p><strong>Protocollo:<\/strong>\u00a0il tossoide tetanico \u00e8 disponibile in Italia unicamente abbinato al vaccino contro l\u2019influenza equina.<\/p>\n<ol>\n<li>somministrazione: intorno al 5\u00b0 mese di vita<\/li>\n<li>somministrazione: dopo 4 \u2013 6 settimane<\/li>\n<li>somministrazione: dopo 12\/18 mesi.<\/li>\n<\/ol>\n<p><em>Titolo anticorpale:<\/em>\u00a0permane per almeno 2\/3 anni dopo il completamento delle vaccinazioni di base ed in alcuni casi anche di pi\u00f9<\/p>\n<p><strong>Test anticorpale:<\/strong> Laboklin dispone di un test sierologico (ELISA semiquantitativa) che permette la quantizzazione del titolo anticorpale per l\u2019anatossina tetanica, che pu\u00f2 essere utilizzato per il monitoraggio della copertura vaccinale.<\/p>\n<h2>Influenza equina<\/h2>\n<p>E\u2019 una malattia virale causata da un virus della famiglia degli <em>Orthomyxoviridae<\/em> molto contagiosa per il cavallo, caratterizzata da una sintomatologia prevalentemente respiratoria, anche se sono possibili le complicanze gastroenteriche. Il virus si trasmette per via aerea attraverso tosse, scoli e starnuti. I soggetti colpiti si ammalano nell\u2019arco di 1\/3 giorni, con febbre e sintomi respiratori e superano generalmente l\u2019infezione nell\u2019arco di una settimana, salvo complicazioni polmonari. La malattia \u00e8 molto diffusiva e per questo motivo il completamento di un corretto piano vaccinale \u00e8 richiesto per tutti gli equini che vengono movimentati per l\u2019uso sportivo.<\/p>\n<p><strong>Protocollo<\/strong>: i vaccini disponibili in Italia comprendono anche il tossoide tetanico ed i ceppi: A\/2South africa, A\/2Newmarket, A\/2Kentucky, A\/2Brentwood, A\/2Borlange.<\/p>\n<p>Si tratta di vaccini ricombinanti od attenuati, da utilizzarsi secondo questo protocollo:<\/p>\n<ol>\n<li>somministrazione: intorno al 5\u00b0\/6\u00b0 mese di vita<\/li>\n<li>somministrazione: dopo 4\u20136 settimane<\/li>\n<li>somministrazione: dopo 12 mesi<\/li>\n<\/ol>\n<p><em>Titolo anticorpale:<\/em>\u00a0permane stabile per circa 6 mesi dopo il completamento delle vaccinazioni di base, fino a non pi\u00f9 di un anno. Questo perch\u00e9 i ceppi utilizzati sono generalmente vecchi ed i virus antinfluenzali sono soggetti ad un rapido \u201cshift antigenico\u201d, quindi la copertura appare minore rispetto al titolo anticorpale prodotto dall\u2019infezione naturale.<\/p>\n<p><strong>Test anticorpale:<\/strong>\u00a0Laboklin offre un test anticorpale (Inibizione dell\u2019emoagglutinazione \u2013 per i ceppi A\/1Prague e A\/2 Newmarket) anche se in letteratura non vi sono dati concordanti nello stabilire quale sia il titolo effettivamente protettivo. Per una corretta diagnosi \u00e8 quindi necessario valutare una sieroconversione dopo 10\u201314 gg.<\/p>\n<h2>Rabbia<\/h2>\n<p>E\u2019 una grave malattia causata da un virus del genere\u00a0<em>Lyssavirus<\/em>, caratterizzata da una sintomatologia nervosa a decorso mortale, trasmissibile anche all\u2019uomo. Il virus si localizza nel sistema nervoso centrale e viene escreto dalle ghiandole salivari, permettendo il contagio tramite il morso o tramite contatto con la saliva di soggetti infetti. Dopo una fase variabile, anche molto lunga, di incubazione, possiamo avere una fase detta <em>prodromica<\/em> (caratterizzata da neurite nella sede della ferita) seguita dalla fase <em>neurologica<\/em>, che nel cavallo pu\u00f2 assumere varie caratteristiche atipiche, non specifiche: turbe del comportamento e della personalit\u00e0, iperattivit\u00e0 ed aggressivit\u00e0, pica, ma anche semplice astenia, zoppie od atassia, spasmo del faringe (idrofobia) con conseguente scialorrea ed alterazioni della fonesi, che evolvono rapidamente in paralisi e morte. Nessuna terapia appare possibile. L\u2019Italia \u00e8 attualmente paese indenne dal 2013, la profilassi antirabbica \u00e8 consigliata a scopo precauzionale negli animali al pascolo nelle zone di confine interessate dagli ultimi casi (Friuli Venezia Giulia, province di Belluno, Trento e Bolzano). \u00c8 stata inoltre mantenuta, sempre in queste zone, la vaccinazione orale nelle volpi.<\/p>\n<p>I vaccini disponibili per il cavallo sono costituiti da virus inattivato, lo schema di somministrazione \u00e8 il seguente:<\/p>\n<ol>\n<li>somministrazione: dopo il 6\u00b0mese di vita<\/li>\n<li>somministrazione: dopo 1\/2 anni, a seconda del prodotto utilizzato<\/li>\n<\/ol>\n<p><em>Titolo anticorpale:<\/em>\u00a0permane per circa 1\/2 anni, anche 3 per alcuni vaccini, dopo il terzo richiamo.<\/p>\n<p><strong>Test anticorpale:<\/strong>\u00a0Laboklin dispone di un test anticorpale (virusneutralizzazione) che viene regolarmente effettuato nei piccoli animali per l\u2019espatrio \u00c8 possibile utilizzarlo per una titolazione post vaccinale anche per il cavallo.<\/p>\n<h2>West Nile Disease<\/h2>\n<p>E\u2019 una patologia di tipo influenzale cui pu\u00f2 seguire una grave encefalite, causata da un virus del genere\u00a0<em>Flavivirus<\/em>, trasmissibile al cavallo, uomo, altri mammiferi da insetti ematofagi, con un ciclo che coinvolge anche alcuni uccelli migratori. Il cavallo \u00e8 un fondo cieco per il virus in quanto la viremia non raggiunge i distretti periferici e la reinfezione ematogena delle zanzare che dovessero pungere un cavallo malato non appare possibile.<\/p>\n<p>L\u2019incubazione dura dai 2 ai 6 giorni. Segue la viremia, che corrisponde al picco febbrile, seguita a sua volta dai sintomi neurologici (atassia, depressione del sensorio, cecit\u00e0, paralisi del posteriore, decubito, \u2026) e da coma e morte nel 25% dei casi. Alcuni animali, dopo la viremia, presentano una remissione dei sintomi e guariscono, con successivo sviluppo di anticorpi (IgM entro i primi 20 giorni, IgG dopo almeno un mese). Da alcuni anni sono disponibili dei vaccini ricombinanti, chimerici od inattivati, protettivi per entrambi i ceppi virali (lineage 1 e lineage 2) circolanti in Europa.<\/p>\n<ol>\n<li>somministrazione: dopo il 6\u00b0 mese di vita, in aprile\/maggio, per avere massima copertura nei mesi estivi<\/li>\n<li>somministrazione: dopo 4 \u2013 6 settimane.<\/li>\n<\/ol>\n<p><em>Titolo anticorpale:<\/em> permane per circa 6 mesi dopo il completamento delle vaccinazioni di base, dopo il sesto mese comincia a calare anche se la protezione dura per almeno un anno.<\/p>\n<p><strong>Test anticorpale:<\/strong>\u00a0possiamo effettuare un test sierologico (Reverse ELISA) che permette di quantizzare sia le IgM, che indicano un\u2019infezione recente in atto (e che quindi permettono al clinico di segnalare la presenza di un focolaio di malattia all\u2019autorit\u00e0 sanitaria competente per territorio) che le IgG, che possono indicare sia un\u2019infezione pregressa che una copertura immunologica di origine vaccinale.<\/p>\n<h2>Herpesvirus equini<\/h2>\n<p>Si tratta di un gruppo di virus che possono dare forme respiratorie altamente contagiose, aborto e forme neurologiche con turbe della deambulazione, paralisi del treno posteriore, disturbi della minzione. Sebbene non vi sia una netta separazione clinico-sintomatologica tra i vari ceppi erpetici, possiamo definire a grandi linee il quadro sintomatologico prevalente per ogni sierovariante:<\/p>\n<ul>\n<li>EHV1: aborto e forma neurologica<\/li>\n<li>EHV2: forme respiratorie lievi, congiuntivite<\/li>\n<li>EHV4: forma respiratoria e sporadicamente neurologica<\/li>\n<li>EHV5: forma polmonare (polmonite interstiziale).<\/li>\n<\/ul>\n<p>Sia la copertura anticorpale vaccinale che quella prodotta dopo superamento della malattia durano 6\u201312 mesi al massimo; la profilassi vaccinale appare parzialmente protettiva per l\u2019aborto e la forma respiratoria ma non protettiva per la forma neurologica.<\/p>\n<p><strong>Protocollo:<\/strong> i vaccini disponibili in Italia comprendono i ceppi EHV1 ed EHV4 (ceppo Kentucky). Si tratta di vaccini attenuati.<\/p>\n<ol>\n<li>somministrazione: intorno al 5\u00b0 mese di vita del puledro<\/li>\n<li>somministrazione: dopo 4\u20136 settimane.<\/li>\n<li>somministrazione: dopo altri 6 mesi.<\/li>\n<\/ol>\n<p><em>Cavalle gravide:\u00a0<\/em>si consigliano tre richiami, al 5\u00b0-7\u00b0-9\u00b0 mese di gestazione, al fine di raggiungere la massima copertura anticorpale tra il 10\u00b0 mese ed il parto, periodo maggiormente a rischio per l\u2019aborto o la natimortalit\u00e0. Questo protocollo permette inoltre la produzione di anticorpi colostrali di pronta disponibilit\u00e0 per il puledro neonato, particolarmente esposto alla forma respiratoria, soprattutto negli allevamenti dove durante i parti si accumulano un gran numero di soggetti in poco tempo.<\/p>\n<p><em>Titolo anticorpale:\u00a0<\/em>permane per circa 6 mesi dopo il completamento del ciclo di vaccinazioni di base, per questo motivo si consiglia di ripetere il vaccino semestralmente o comunque ad ogni gravidanza nelle fattrici.<\/p>\n<p><strong>Test anticorpale:<\/strong> Laboklin dispone di test anticorpali per tutte cinque le varianti erpetiche (IFAT), la diagnosi sierologica \u00e8 attendibile solo dopo valutazione di una idonea sieroconversione, al fine di dimostrare il deciso incremento degli anticorpi nella fase acuta della malattia, che di solito coincide con la forma respiratoria (viremia). Nelle forme abortive, che possono seguire la fase respiratoria a distanza variabile, potremmo non avere un deciso picco anticorpale poich\u00e9 il siero prelevato al momento dell\u2019aborto non indica la fase acuta ma piuttosto una fase di convalescenza.<\/p>\n<p style=\"text-align: right;\"><strong>Dott.ssa Susanna Mereghetti<\/strong><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;vc_default&#8221; gap=&#8221;10&#8243; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; css=&#8221;.vc_custom_1699524647911{margin-top: 30px !important;}&#8221;][vc_column width=&#8221;1\/6&#8243; css=&#8221;.vc_custom_1725536315041{background-color: #e7e7e7 !important;}&#8221;][vc_icon icon_fontawesome=&#8221;fas fa-file-pdf&#8221; color=&#8221;custom&#8221; size=&#8221;xl&#8221; align=&#8221;center&#8221; css=&#8221;.vc_custom_1725536320619{margin-top: 10px !important;margin-bottom: 10px !important;padding-top: 20px !important;padding-bottom: 20px !important;}&#8221; custom_color=&#8221;#e51e1e&#8221; link=&#8221;url:https%3A%2F%2Flaboklin.com%2Fwp-content%2Fuploads%2F2023%2F03%2F2021_01_Vaccini-e-test-sierologici-nel-cavallo.pdf|target:_blank&#8221;][\/vc_column][vc_column width=&#8221;5\/6&#8243; css=&#8221;.vc_custom_1725536331161{background-color: #e7e7e7 !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1725536336406{margin-top: 10px !important;margin-bottom: 10px !important;padding-top: 20px !important;padding-bottom: 20px !important;}&#8221;]<a href=\"https:\/\/laboklin.com\/wp-content\/uploads\/2023\/03\/2021_01_Vaccini-e-test-sierologici-nel-cavallo.pdf\" target=\"_blank\" rel=\"noopener\"><strong>Vaccini e test sierologici nel cavallo<\/strong><\/a>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Nella clinica ippiatrica abbiamo a disposizione alcuni vaccini per la prevenzione di patologie virali e batteriche; questi protocolli vaccinali possono interferire nella diagnostica sierologica anticorpale \u2013 vediamo come e per quali malattie.<\/p>\n","protected":false},"author":29,"featured_media":1460559,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"none","_seopress_titles_title":"Vaccini e test sierologici nel cavallo","_seopress_titles_desc":"Nella clinica ippiatrica abbiamo a disposizione alcuni vaccini per la prevenzione di patologie virali e batteriche; questi protocolli vaccinali possono interferire nella diagnostica sierologica anticorpale \u2013 vediamo come e per quali malattie.","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":""},"categories":[455],"tags":[],"class_list":["post-1466386","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aggiornamenti-laboklin-cavallo-camelidi-2021","category-455","description-off"],"_links":{"self":[{"href":"https:\/\/laboklin.com\/it\/wp-json\/wp\/v2\/posts\/1466386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laboklin.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laboklin.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laboklin.com\/it\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/laboklin.com\/it\/wp-json\/wp\/v2\/comments?post=1466386"}],"version-history":[{"count":9,"href":"https:\/\/laboklin.com\/it\/wp-json\/wp\/v2\/posts\/1466386\/revisions"}],"predecessor-version":[{"id":1518298,"href":"https:\/\/laboklin.com\/it\/wp-json\/wp\/v2\/posts\/1466386\/revisions\/1518298"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laboklin.com\/it\/wp-json\/wp\/v2\/media\/1460559"}],"wp:attachment":[{"href":"https:\/\/laboklin.com\/it\/wp-json\/wp\/v2\/media?parent=1466386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laboklin.com\/it\/wp-json\/wp\/v2\/categories?post=1466386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laboklin.com\/it\/wp-json\/wp\/v2\/tags?post=1466386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}