{"id":1439836,"date":"2021-10-08T10:58:04","date_gmt":"2021-10-08T08:58:04","guid":{"rendered":"https:\/\/staging-wp-int.laboklin.com\/?p=1439836"},"modified":"2024-09-05T13:28:55","modified_gmt":"2024-09-05T11:28:55","slug":"laiuto-del-laboratorio-per-la-gestione-della-gravidanza-a-rischio-nella-fattrice-parte-2","status":"publish","type":"post","link":"https:\/\/laboklin.com\/it\/laiuto-del-laboratorio-per-la-gestione-della-gravidanza-a-rischio-nella-fattrice-parte-2\/","title":{"rendered":"L&#8217;aiuto del laboratorio per la gestione della gravidanza a rischio nella fattrice (parte2)"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]Quando ci troviamo di fronte ad una fattrice con gravidanza a rischio oltre che monitorare attentamente la fase di maturazione fetale, appare di fondamentale importanza organizzare un\u2019adeguata assistenza al parto con l\u2019ausilio di telecamere, allarmi e personale preparato.<\/p>\n<p>Non sempre infatti le cavalle mostrano i classici segni di parto imminente, soprattutto se primipare: perdita del tappo mucoso, rilassamento dei legamenti sacroischiatici della coda e dei muscoli glutei, abbassamento dell\u2019addome, ingrossamento della vena e del parenchima mammario, formazione delle \u201ccere\u201d (gocce di colostro coagulato) a livello di capezzoli o addirittura perdita di piccole quantit\u00e0 dello stesso poco prima del parto.<\/p>\n<p>Negli ultimi anni si \u00e8 sviluppata una metodica piuttosto semplice che pu\u00f2 agevolare il personale nel riconoscere l\u2019avvicinarsi del parto, oppure pu\u00f2 dare delle indicazioni chiare al veterinario che si trovi a dover indurre il parto medesimo per i pi\u00f9 svariati motivi: <strong>il controllo della concentrazione di alcuni elettroliti nelle secrezioni mammarie antecedenti la produzione di colostro e latte.<\/strong><\/p>\n<p>Si utilizzano 1,5\u20132 ml di secrezioni raccogliendole in un piccolo contenitore, preferibilmente alla sera dopo le 17:00, poi si aggiunge dell\u2019acqua distillata in proporzioni 1:6 e di seguito si mescola con i reagenti o si immerge nella soluzione la striscetta misuratrice, a seconda del tipo di test prescelto.<\/p>\n<h2>Secrezioni mammarie<\/h2>\n<p>Il monitoraggio di queste secrezioni fornisce un indice attendibile di maturazione fetale. Per innescare le contrazioni uterine risulta indispensabile la presenza di un livello ematico adeguato di Ca, Na e K che si riflette appunto nelle secrezioni ghiandolari mammarie, il tutto ovviamente in condizioni di normalit\u00e0.<\/p>\n<p>Per il Ca lo schema rilevato \u00e8 il seguente:<\/p>\n<ul>\n<li>fino a 200 ppm: parto non imminente, si consiglia di ripetere il test ogni 24 ore<\/li>\n<li>tra 200 e 350 ppm: il puledro ha raggiunto la maturit\u00e0 e questo \u00e8 considerato un range sicuro per un\u2019eventuale induzione, si consiglia di applicare l\u2019 allarme parto se disponibile e ripetere il test ogni 12\/24 ore<\/li>\n<li>oltre 350 ppm: parto imminente<\/li>\n<\/ul>\n<p>Questa misurazione \u00e8 effettuabile in campo in modo veloce ed economico tramite i kit della durezza dell\u2019acqua (Dupla, Sera, Merckoquant, Foal watch, Aquadur, &#8230;) con soluzioni o striscette che virano di colore; il punto chiave infatti \u00e8 il l\u2019utilizzo regolare 1 o 2 volte al giorno, tutti i giorni senza eccezioni dal momento che si rilevano le prime secrezioni fino a parto avvenuto.<\/p>\n<p>Questo parametro ha per\u00f2 maggiore attendibilit\u00e0 in senso negativo: quasi nessuna fattrice partorisce con livelli di Ca inferiore a 200 ppm. Una volta superata la soglia dei 350 ppm sappiamo che il feto \u00e8 pronto per il parto ma le tempistiche sono alquanto variabili.<\/p>\n<p>Il parto pu\u00f2 avvenire da 1\u20133 giorni fino a 7\u201310 giorni dopo il superamento, specialmente nelle fattrici che tendono a perdere latte. Le primipare possono invece partorire con livelli di Ca pi\u00f9 bassi.<\/p>\n<p>La presenza di patologie placentari pu\u00f2 condizionare negativamente la maturazione dell\u2019attivit\u00e0 secretoria. In questi casi la misurazione degli elettroliti non risulta indicativa.<\/p>\n<p>Congiuntamente all\u2019innalzamento dei livelli di calcio, si assiste all\u2019inversione del rapporto tra Na e K: dopo che si verifica questa inversione (con abbassamento repentino del Na &lt;30 mmol\/L ed un innalzamento rapido del K &gt;35 mmol\/L) il parto avviene solitamente entro 24\/48 ore nella maggior parte delle fattrici.<\/p>\n<p>Per questi due elettroliti non vi sono a disposizione kit attendibili per poter effettuare queste misurazioni in campo. Un\u2019approssimazione dell\u2019avvenuta inversione del rapporto tra Na e K si ottiene con la misurazione del pH, per il quale possiamo utilizzare delle pratiche cartine tornasole od anche un phmetro portatile, con un costo contenuto.<\/p>\n<h2>Misurazione del pH<\/h2>\n<p>La misurazione del pH si effettua in modo rapido, economico e sicuro e necessita di scarsissime quantit\u00e0 di secreto ed \u00e8 quindi attuabile in pratica anche con soggetti poco collaborativi.<\/p>\n<p>\u00c8 possibile utilizzare le normali cartine tornasole in vendita nelle farmacie oppure online. Queste devono avere un range tra 5 e 8 e mostrare un chiaro cambiamento di colore tra 7 e 6 (sono i valori che devono essere distinti nel modo pi\u00f9 chiaro possibile).<\/p>\n<p>Le variazioni elettrolitiche che determinano nel complesso un abbassamento del pH procedono secondo tre pi\u00f9 comuni schemi:<\/p>\n<ul>\n<li><em>fattrici primipare giovani:<\/em> possono passare da un pH 7,5 ad un pH 6,8\u20136,5 nell\u2019arco di 24\u201312 ore e poi partorire durante la notte<\/li>\n<li><em>fattrici pluripare oppure \u201cold maiden\u201d:<\/em> di solito il pH si abbassa molto lentamente da 7,5 fino a 6,4\u20136,2 con andamento non sempre lineare<\/li>\n<li><em>fattrici che partoriscono con pH alcalino:<\/em> evenienza rara ma possibile.<\/li>\n<\/ul>\n<p>\u00c8 implicito che queste misurazioni non possono dare delle sicurezze ma sono state concepite per agevolare la gestione dell\u2019allevamento e vanno utilizzate congiuntamente e non in sostituzione di un\u2019attenta osservazione e dell\u2019utilizzo di allarmi elettronici. Sappiamo infatti che il parto nella cavalla deve avvenire in modo rapido ed i primi minuti \/ le prime ore di vita del puledro devono essere monitorati attentamente per evitare quanto pi\u00f9 possibile spiacevoli conseguenze sia per la fattrice che per il redo.<\/p>\n<p style=\"text-align: right;\"><strong>Dott.ssa Susanna Mereghetti<\/strong><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;vc_default&#8221; gap=&#8221;10&#8243; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; css=&#8221;.vc_custom_1699444123207{margin-top: 30px !important;}&#8221;][vc_column width=&#8221;1\/6&#8243; css=&#8221;.vc_custom_1725535676300{background-color: #e7e7e7 !important;}&#8221;][vc_icon icon_fontawesome=&#8221;fas fa-file-pdf&#8221; color=&#8221;custom&#8221; size=&#8221;xl&#8221; align=&#8221;center&#8221; css=&#8221;.vc_custom_1725535695216{margin-top: 10px !important;margin-bottom: 10px !important;padding-top: 20px !important;padding-bottom: 20px !important;}&#8221; custom_color=&#8221;#e51e1e&#8221; link=&#8221;url:https%3A%2F%2Flaboklin.com%2Fwp-content%2Fuploads%2F2023%2F03%2F2021_10_Il-laboratorio-nella-gravidanza-a-rischio-parte-2.pdf|target:_blank&#8221;][\/vc_column][vc_column width=&#8221;5\/6&#8243; css=&#8221;.vc_custom_1725535708942{background-color: #e7e7e7 !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1725535716796{margin-top: 10px !important;margin-bottom: 10px !important;padding-top: 20px !important;padding-bottom: 20px !important;}&#8221;]<a href=\"https:\/\/laboklin.com\/wp-content\/uploads\/2023\/03\/2021_10_Il-laboratorio-nella-gravidanza-a-rischio-parte-2.pdf\" target=\"_blank\" rel=\"noopener\"><strong>L&#8217;aiuto del laboratorio per la gestione della gravidanza a rischio nella fattrice (parte2)<\/strong><\/a>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Quando ci troviamo di fronte ad una fattrice con gravidanza a rischio oltre che monitorare attentamente la fase di maturazione fetale, appare di fondamentale importanza organizzare un\u2019adeguata assistenza al parto con l\u2019ausilio di telecamere, allarmi e personale preparato.<\/p>\n","protected":false},"author":29,"featured_media":1460559,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"none","_seopress_titles_title":"","_seopress_titles_desc":"Quando ci troviamo di fronte ad una fattrice con gravidanza a rischio oltre che monitorare attentamente la fase di maturazione fetale, appare di fondamentale importanza organizzare un\u2019adeguata assistenza al parto con l\u2019ausilio di telecamere, allarmi e personale preparato.","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":""},"categories":[455],"tags":[],"class_list":["post-1439836","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aggiornamenti-laboklin-cavallo-camelidi-2021","category-455","description-off"],"_links":{"self":[{"href":"https:\/\/laboklin.com\/it\/wp-json\/wp\/v2\/posts\/1439836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laboklin.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laboklin.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laboklin.com\/it\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/laboklin.com\/it\/wp-json\/wp\/v2\/comments?post=1439836"}],"version-history":[{"count":10,"href":"https:\/\/laboklin.com\/it\/wp-json\/wp\/v2\/posts\/1439836\/revisions"}],"predecessor-version":[{"id":1518291,"href":"https:\/\/laboklin.com\/it\/wp-json\/wp\/v2\/posts\/1439836\/revisions\/1518291"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laboklin.com\/it\/wp-json\/wp\/v2\/media\/1460559"}],"wp:attachment":[{"href":"https:\/\/laboklin.com\/it\/wp-json\/wp\/v2\/media?parent=1439836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laboklin.com\/it\/wp-json\/wp\/v2\/categories?post=1439836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laboklin.com\/it\/wp-json\/wp\/v2\/tags?post=1439836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}