
{"id":1429134,"date":"2021-03-29T11:03:47","date_gmt":"2021-03-29T09:03:47","guid":{"rendered":"https:\/\/staging-wp-int.laboklin.com\/fvo-tagung\/"},"modified":"2021-03-29T11:03:47","modified_gmt":"2021-03-29T09:03:47","slug":"fvo-tagung","status":"publish","type":"page","link":"https:\/\/laboklin.com\/fr\/fvo-tagung\/","title":{"rendered":"FVO Tagung"},"content":{"rendered":"<h3>FVO-Tagung, 17.04.2021<\/h3>\n<p>&nbsp;<\/p>\n<p>Spannende Vortr\u00e4ge! Trotzdem noch wissensdurstig?<\/p>\n<p>Zumindest in Sachen Labordiagnostik rund ums Auge k\u00f6nnen wir Ihnen da behilflich sein:<\/p>\n<p>Wir haben Informationsmaterial f\u00fcr die Praxis zusammengestellt, bestimmt ist etwas N\u00fctzliches f\u00fcr Sie dabei:<\/p>\n<p>Unsere Mappe \u201eLabordiagnostik bei Erkrankungen des Auges\u201c beschreibt die labordiagnostischen Untersuchungsm\u00f6glichkeiten des Organs Auge: von der Mikrobiologie \u00fcber PCR-Profile hin zu den Untersuchungen auf erblich bedingte Erkrankungen.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/laboklin.com\/wp-content\/uploads\/sites\/2\/2021\/04\/Labordiagnostik_Auge.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1308248 size-medium\" src=\"https:\/\/laboklin.com\/wp-content\/uploads\/sites\/2\/2021\/04\/Labordiagnostik_Auge-300x292.png\" alt=\"\" width=\"300\" height=\"292\" srcset=\"https:\/\/laboklin.com\/wp-content\/uploads\/2021\/04\/Labordiagnostik_Auge-300x292.png 300w, https:\/\/laboklin.com\/wp-content\/uploads\/2021\/04\/Labordiagnostik_Auge-768x748.png 768w, https:\/\/laboklin.com\/wp-content\/uploads\/2021\/04\/Labordiagnostik_Auge.png 937w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Einen schnellen \u00dcberblick speziell \u00fcber die Tests genetisch bedingten Augenerkrankungen verschaffen Sie sich anhand unserer tabellarischen Auflistung.<\/p>\n<p>Und zur Auslage in Ihrer Praxis f\u00fcr die Tierhalter haben wir unseren Rat&amp;Tat-Folder \u201eUntersuchungen bei Augenkrankheiten\u201c auf den neuesten Stand gebracht.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/laboklin.com\/wp-content\/uploads\/sites\/2\/2021\/04\/rat_und_tat.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1308247 size-medium\" src=\"https:\/\/laboklin.com\/wp-content\/uploads\/sites\/2\/2021\/04\/rat_und_tat-300x213.png\" alt=\"\" width=\"300\" height=\"213\" srcset=\"https:\/\/laboklin.com\/wp-content\/uploads\/2021\/04\/rat_und_tat-300x213.png 300w, https:\/\/laboklin.com\/wp-content\/uploads\/2021\/04\/rat_und_tat-1024x728.png 1024w, https:\/\/laboklin.com\/wp-content\/uploads\/2021\/04\/rat_und_tat-768x546.png 768w, https:\/\/laboklin.com\/wp-content\/uploads\/2021\/04\/rat_und_tat.png 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Auf Wunsch schicken wir Ihnen diese Unterlagen gerne einzeln oder als Gesamtpaket zu.<\/p>\n<p><strong>Dokumente als PDF anfordern:<\/strong><br \/>\n[super_form i18n=\u00a0\u00bbde_DE_formal\u00a0\u00bb id=\u00a0\u00bb1308155&Prime;]<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Dokumente per Post anfordern:<\/strong><\/p>\n<p>[super_form i18n=\u00a0\u00bbde_DE_formal\u00a0\u00bb id=\u00a0\u00bb1308276&Prime;]<\/p>\n<p>&nbsp;<\/p>\n<div style=\"color: white;padding: 15px\">\n<strong>Zus\u00e4tzlich w\u00fcrden wir Sie gerne zu einem englischsprachigen Webinar der ECVO am 22.4. um 21:00 Uhr mit dem Titel: Hereditary Eye Diseases in Italian breeds von und mit dem Referenten Adolfo Guandalini einladen. Unser Engagement bei der ECVO macht es uns m\u00f6glich, Ihnen eine Teilnahme anzubieten.<\/strong><\/p>\n<p><strong>Interesse? Registrieren Sie sich kostenfrei unter folgendem Link: <a style=\"color: #344251\" href=\"https:\/\/laboklin.zoom.us\/webinar\/register\/WN_86B8JH5wQzeCeZqDGs9QEg\" target=\"_blank\" rel=\"noopener\">https:\/\/laboklin.zoom.us\/webinar\/register\/WN_86B8JH5wQzeCeZqDGs9QEg<\/a><\/strong>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>FVO-Tagung, 17.04.2021 &nbsp; Spannende Vortr\u00e4ge! Trotzdem noch wissensdurstig? Zumindest in Sachen Labordiagnostik rund ums Auge k\u00f6nnen wir Ihnen da behilflich sein: Wir haben Informationsmaterial f\u00fcr die Praxis zusammengestellt, bestimmt ist etwas N\u00fctzliches f\u00fcr Sie dabei: Unsere Mappe \u201eLabordiagnostik bei Erkrankungen des Auges\u201c beschreibt die labordiagnostischen Untersuchungsm\u00f6glichkeiten des Organs Auge: von der Mikrobiologie \u00fcber PCR-Profile hin&hellip;<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":14,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":""},"class_list":["post-1429134","page","type-page","status-publish","hentry","description-off"],"_links":{"self":[{"href":"https:\/\/laboklin.com\/fr\/wp-json\/wp\/v2\/pages\/1429134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laboklin.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/laboklin.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/laboklin.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/laboklin.com\/fr\/wp-json\/wp\/v2\/comments?post=1429134"}],"version-history":[{"count":0,"href":"https:\/\/laboklin.com\/fr\/wp-json\/wp\/v2\/pages\/1429134\/revisions"}],"wp:attachment":[{"href":"https:\/\/laboklin.com\/fr\/wp-json\/wp\/v2\/media?parent=1429134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}